{"id":1665,"date":"2018-10-15T08:40:40","date_gmt":"2018-10-15T08:40:40","guid":{"rendered":"https:\/\/www.inforesidencias.com\/blog\/wp-content\/uploads\/2018\/10\/preso-edad-avanzada.jpg"},"modified":"2018-10-15T08:40:40","modified_gmt":"2018-10-15T08:40:40","slug":"preso-edad-avanzada","status":"inherit","type":"attachment","link":"https:\/\/www.inforesidencias.com\/blog\/index.php\/2018\/10\/16\/las-personas-de-edad-avanzada-en-las-prisiones\/preso-edad-avanzada\/","title":{"rendered":"preso edad avanzada"},"author":2,"comment_status":"open","ping_status":"open","template":"","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>preso edad avanzada - Blog Inforesidencias.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.inforesidencias.com\/blog\/wp-content\/uploads\/2018\/10\/preso-edad-avanzada.jpg\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"preso edad avanzada - Blog Inforesidencias.com\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.inforesidencias.com\/blog\/wp-content\/uploads\/2018\/10\/preso-edad-avanzada.jpg\" \/>\n<meta property=\"og:site_name\" content=\"Blog Inforesidencias.com\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Inforesidencias\/\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.inforesidencias.com\/blog\/wp-content\/uploads\/2018\/10\/preso-edad-avanzada.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"604\" \/>\n\t<meta property=\"og:image:height\" content=\"340\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@inforesidencias\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.inforesidencias.com\/blog\/wp-content\/uploads\/2018\/10\/preso-edad-avanzada.jpg\",\"url\":\"https:\/\/www.inforesidencias.com\/blog\/wp-content\/uploads\/2018\/10\/preso-edad-avanzada.jpg\",\"name\":\"preso edad avanzada - Blog Inforesidencias.com\",\"isPartOf\":{\"@id\":\"https:\/\/www.inforesidencias.com\/blog\/#website\"},\"datePublished\":\"2018-10-15T08:40:40+00:00\",\"dateModified\":\"2018-10-15T08:40:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.inforesidencias.com\/blog\/wp-content\/uploads\/2018\/10\/preso-edad-avanzada.jpg#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.inforesidencias.com\/blog\/wp-content\/uploads\/2018\/10\/preso-edad-avanzada.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.inforesidencias.com\/blog\/wp-content\/uploads\/2018\/10\/preso-edad-avanzada.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.inforesidencias.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Las personas de edad avanzada en las prisiones\",\"item\":\"https:\/\/www.inforesidencias.com\/blog\/index.php\/2018\/10\/16\/las-personas-de-edad-avanzada-en-las-prisiones\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"preso edad avanzada\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.inforesidencias.com\/blog\/#website\",\"url\":\"https:\/\/www.inforesidencias.com\/blog\/\",\"name\":\"Blog Inforesidencias.com\",\"description\":\"El buscador de residencias de la 3\u00aa edad\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.inforesidencias.com\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"preso edad avanzada - Blog Inforesidencias.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.inforesidencias.com\/blog\/wp-content\/uploads\/2018\/10\/preso-edad-avanzada.jpg","og_locale":"es_ES","og_type":"article","og_title":"preso edad avanzada - Blog Inforesidencias.com","og_url":"https:\/\/www.inforesidencias.com\/blog\/wp-content\/uploads\/2018\/10\/preso-edad-avanzada.jpg","og_site_name":"Blog Inforesidencias.com","article_publisher":"https:\/\/www.facebook.com\/Inforesidencias\/","og_image":[{"width":604,"height":340,"url":"https:\/\/www.inforesidencias.com\/blog\/wp-content\/uploads\/2018\/10\/preso-edad-avanzada.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@inforesidencias","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.inforesidencias.com\/blog\/wp-content\/uploads\/2018\/10\/preso-edad-avanzada.jpg","url":"https:\/\/www.inforesidencias.com\/blog\/wp-content\/uploads\/2018\/10\/preso-edad-avanzada.jpg","name":"preso edad avanzada - Blog Inforesidencias.com","isPartOf":{"@id":"https:\/\/www.inforesidencias.com\/blog\/#website"},"datePublished":"2018-10-15T08:40:40+00:00","dateModified":"2018-10-15T08:40:40+00:00","breadcrumb":{"@id":"https:\/\/www.inforesidencias.com\/blog\/wp-content\/uploads\/2018\/10\/preso-edad-avanzada.jpg#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.inforesidencias.com\/blog\/wp-content\/uploads\/2018\/10\/preso-edad-avanzada.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.inforesidencias.com\/blog\/wp-content\/uploads\/2018\/10\/preso-edad-avanzada.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.inforesidencias.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Las personas de edad avanzada en las prisiones","item":"https:\/\/www.inforesidencias.com\/blog\/index.php\/2018\/10\/16\/las-personas-de-edad-avanzada-en-las-prisiones\/"},{"@type":"ListItem","position":3,"name":"preso edad avanzada"}]},{"@type":"WebSite","@id":"https:\/\/www.inforesidencias.com\/blog\/#website","url":"https:\/\/www.inforesidencias.com\/blog\/","name":"Blog Inforesidencias.com","description":"El buscador de residencias de la 3\u00aa edad","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.inforesidencias.com\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.inforesidencias.com\/blog\/wp-content\/uploads\/2018\/10\/preso-edad-avanzada.jpg'><img loading=\"lazy\" width=\"300\" height=\"169\" src=\"https:\/\/www.inforesidencias.com\/blog\/wp-content\/uploads\/2018\/10\/preso-edad-avanzada.jpg\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":604,"height":340,"file":"2018\/10\/preso-edad-avanzada.jpg","image_meta":{"aperture":0,"credit":"","camera":"","caption":"","created_timestamp":0,"copyright":"","focal_length":0,"iso":0,"shutter_speed":0,"title":"","orientation":0},"sizes":{}},"post":1661,"source_url":"https:\/\/www.inforesidencias.com\/blog\/wp-content\/uploads\/2018\/10\/preso-edad-avanzada.jpg","_links":{"self":[{"href":"https:\/\/www.inforesidencias.com\/blog\/index.php\/wp-json\/wp\/v2\/media\/1665"}],"collection":[{"href":"https:\/\/www.inforesidencias.com\/blog\/index.php\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.inforesidencias.com\/blog\/index.php\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.inforesidencias.com\/blog\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.inforesidencias.com\/blog\/index.php\/wp-json\/wp\/v2\/comments?post=1665"}]}}